{"id":6448,"date":"2014-09-21T17:17:03","date_gmt":"2014-09-21T15:17:03","guid":{"rendered":"http:\/\/blogs.bl0rg.net\/finis_africae\/?p=6448"},"modified":"2018-09-29T11:04:50","modified_gmt":"2018-09-29T09:04:50","slug":"kro-252","status":"publish","type":"post","link":"http:\/\/blogs.bl0rg.net\/finis_africae\/2014\/09\/21\/kro-252\/","title":{"rendered":"Kro"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2014\/09\/10533721_10152647985848469_8302252807182389343_n-2014-09-21-17-17.jpg\" alt=\"10533721_10152647985848469_8302252807182389343_n-2014-09-21-17-17.jpg\" width=\"177\" height=\"224\" \/><\/p>\n<p style=\"text-align: left;\">Netflix est arriv\u00e9. Nous avons donc aussit\u00f4t tourn\u00e9 le dos \u00e0 Canal play, qui n\u2019arr\u00eate pas de planter au point que parfois, on a renonc\u00e9 \u00e0 regarder la t\u00e9l\u00e9. On est pass\u00e9 \u00e0 Netflix. On peut faire un match : catalogue contre catalogue, mais le premier avantage en tout cas, c\u2019est que Netflix, c\u2019est ergonomique et stable, tout ce que Canal play n\u2019est pas, n\u2019\u00e9tait pas en passe de devenir, se moquant \u00e9perdument de ses clients, rapport qu\u2019ils \u00e9taient un peu tout seul sur leur cr\u00e9neau, sans \u00eatre un service public.<\/p>\n<p style=\"text-align: left;\">Commenc\u00e9 p\u00e9niblement sur Canal play et poursuivi sur Netflix :<\/p>\n<p style=\"text-align: left;\">S\u00e9rie : Luther (Saison 1 et 2) de Neil Cross avec Idris Alba<\/p>\n<p style=\"text-align: left;\">Film : Sin City : J\u2019ai tu\u00e9 pour elle de Franck Miller avec Mickey Rourke, Jessica Alba, Eva Green, Josh Brolin, Bruce Willis<\/p>\n<p style=\"text-align: left;\">BD : La France en rose et bleu par Nawak<\/p>\n<p style=\"text-align: left;\"><!--more--><\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2014\/09\/p01bzlgc-2014-09-21-17-17.jpg\" alt=\"p01bzlgc-2014-09-21-17-17.jpg\" width=\"316\" height=\"177\" \/><strong>Luther de Neil Cross avec Idriss Alba et Ruth Wilson<\/strong><\/p>\n<p style=\"text-align: left;\">Nous cherchions une nouvelle s\u00e9rie \u00e0 tester. Ce qui nous a attir\u00e9 avec Luther, c\u2019est que c\u2019\u00e9tait des saisons courtes.  <a href=\"https:\/\/www.nicn.fr\/\">moncler paris<\/a> Les saisons en 22 \u00e9pisodes avec un coup mou au milieu et \u00e7a traine, on en avait un peu assez.<\/p>\n<p style=\"text-align: left;\">Luther, c\u2019est 3 saisons, 6, 4 et 4 \u00e9pisodes.<\/p>\n<p style=\"text-align: left;\">John Luther est policier \u00e0 Londres dans la section criminelle.  <a href=\"http:\/\/www.boulogne-vendee.fr\/\">puma 2018 shop<\/a> Il s\u2019est beaucoup investi dans la recherche d\u2019un meurtrier d\u2019enfants, jusqu\u2019\u00e0 ce qu\u2019il le coince et permette que sa derni\u00e8re victime soit sauv\u00e9e&#8230; Mais il laisse tomber le meurtrier d\u2019un \u00e9chafaudage et sombre en d\u00e9pression pendant que le meurtrier sombre dans le coma.<\/p>\n<p style=\"text-align: left;\">Lors de sa premi\u00e8re affaire \u00e0 son retour au travail, il rencontre une jeune femme surdou\u00e9e dont les parents ont \u00e9t\u00e9 abattus. Il comprend vite qu\u2019elle est la meurtri\u00e8re mais ne peut le prouver.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2014\/09\/luther-2014-09-21-17-17.png\" alt=\"luther-2014-09-21-17-17.png\" width=\"501\" height=\"392\" \/><\/p>\n<p style=\"text-align: left;\">C\u2019est une s\u00e9rie dont le pilote ne m\u2019a pas accroch\u00e9 du tout et a m\u00eame failli me faire renoncer \u00e0 la s\u00e9rie. Ce pilote met les \u00e9l\u00e9ments en place mais ne donne pas vraiment le rythme des \u00e9pisodes suivants.  <a href=\"https:\/\/www.hotel-castel.fr\/ugg-outlet-france.html\">ugg outlet france<\/a> Donc, ne pas se d\u00e9courager.<\/p>\n<p style=\"text-align: left;\">Luther est un flic borderline, qui comprend tr\u00e8s bien la psychologie des meurtriers et qui, au bout d\u2019un moment, a juste envie de les enlever de la plan\u00e8te.<\/p>\n<p style=\"text-align: left;\">Les histoires sont construites comme les Colombo, on connait le meurtrier au d\u00e9but, l\u2019int\u00e9r\u00eat est de voir comment Luther va \u00eatre plus fort que lui.  <a href=\"https:\/\/www.alt-i.fr\/timberland-chaussures.html\">timberland chaussures<\/a> Le fil rouge, c\u2019est la jeune meurtri\u00e8re, qui a d\u00e9couvert que Luther \u00e9tait le seul homme capable de la pi\u00e9ger mais aussi de la comprendre, de penser comme elle. Et bien s\u00fbr au bout d\u2019un moment, Luther va bien comprendre qu\u2019elle est la seule \u00e0 vraiment le comprendre&#8230;<\/p>\n<p style=\"text-align: left;\">D\u2019\u00e9pisode en \u00e9pisode, on visite Londres sous bien des angles, en poursuivant toute sorte de meurtriers en s\u00e9rie.<\/p>\n<p style=\"text-align: left;\">Le plus de cette s\u00e9rie, c\u2019est la qualit\u00e9 des acteurs, Idris Alba et Ruth Wilson sont formidables, mais tous les seconds r\u00f4les sont \u00e9galement formidables.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2014\/09\/323812-2014-09-21-17-17.jpg\" alt=\"323812-2014-09-21-17-17.jpg\" width=\"160\" height=\"213\" \/><strong>Sin City : J\u2019ai tu\u00e9 pour elle de Franck Miller avec Mickey Rourke, Jessica Alba, Eva Green, Josh Brolin, Bruce Willis<\/strong><\/p>\n<p style=\"text-align: left;\">Tout l\u2019int\u00e9r\u00eat de Sin City (du 1 comme du 2), c\u2019est son environnement graphique.  <a href=\"http:\/\/www.bestofindia.fr\/\">Baskets Puma<\/a> Du noir et blanc dur, avec des \u00e9l\u00e9ments coloris\u00e9s et des d\u00e9cors qui ressemblent fortement \u00e0 de la BD.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2014\/09\/ava-2014-09-21-17-17.png\" alt=\"ava-2014-09-21-17-17.png\" width=\"494\" height=\"305\" \/><\/p>\n<p style=\"text-align: left;\">L\u2019histoire est assez d\u00e9cousue.  <a href=\"http:\/\/www.bestofindia.fr\/\">soldes puma sneakers<\/a> L\u2019ambiance, c\u2019est du polar noir, avec des hommes au bout du rouleau, qui ont grandi dans les bas quartiers et qui ne croient plus en rien. Des filles superbes qui essaient de survivre comme elles peuvent, souvent au moyen de leur corps, avec plus ou moins de classe.<\/p>\n<p style=\"text-align: left;\">Des beaut\u00e9s v\u00e9n\u00e9neuses devant lesquelles ces hommes, qui tueraient de sang froid sans ciller, ne sont plus rien.<\/p>\n<p style=\"text-align: left;\">A cela on ajoute un peu de mise en sc\u00e8ne \u00e0 la \u00ab Kill Bill \u00bb, du sang qui gicle (en blanc) des combattantes extraordinairement dou\u00e9es, des m\u00e9chants au physique de m\u00e9chant improbable, et pas d\u2019espoir en ville, si ce n\u2019est parfois, une certaine loyaut\u00e9, encore entretenue par ceux et celles qui sont les ma\u00eetres de ces bas-fonds, bien plus moraux que la police ou les notables.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2014\/09\/352342-2014-09-21-17-17.jpg\" alt=\"352342-2014-09-21-17-17.jpg\" width=\"561\" height=\"364\" \/><\/p>\n<p style=\"text-align: left;\">Honn\u00eatement, on s\u2019ennuie un peu dans Sin City, parce que l\u2019ambiance en soit ne permet pas de nous occuper pendant presque deux heures. Mais c\u2019est beau. Et la 3D aussi est belle&#8230; on a juste l\u2019impression que les efforts du r\u00e9alisateur s\u2019essoufflent au bout d\u2019une heure de film.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2014\/09\/Couverture-recto-300x300-2014-09-21-17-17.jpg\" alt=\"Couverture-recto-300x300-2014-09-21-17-17.jpg\" width=\"239\" height=\"239\" \/><strong>La France en rose et bleu par Nawak<\/strong><\/p>\n<p style=\"text-align: left;\">Nawak fait du dessin de presse.  <a href=\"https:\/\/www.manaespresso.fr\/sitemap.xml\">bottes ugg<\/a> Derni\u00e8rement, les d\u00e9lires de la manif pour tous l\u2019ont pas mal fatigu\u00e9. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Netflix est arriv\u00e9. Nous avons donc aussit\u00f4t tourn\u00e9 le dos \u00e0 Canal play, qui n\u2019arr\u00eate pas de planter au point que parfois, on a renonc\u00e9 \u00e0 regarder la t\u00e9l\u00e9. On est pass\u00e9 \u00e0 Netflix. On peut faire un match : &hellip; <a href=\"http:\/\/blogs.bl0rg.net\/finis_africae\/2014\/09\/21\/kro-252\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,11,9],"tags":[30,22,52],"_links":{"self":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/6448"}],"collection":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/comments?post=6448"}],"version-history":[{"count":4,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/6448\/revisions"}],"predecessor-version":[{"id":8527,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/6448\/revisions\/8527"}],"wp:attachment":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/media?parent=6448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/categories?post=6448"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/tags?post=6448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}