{"id":6858,"date":"2015-09-01T22:09:06","date_gmt":"2015-09-01T20:09:06","guid":{"rendered":"http:\/\/blogs.bl0rg.net\/finis_africae\/?p=6858"},"modified":"2018-09-29T11:04:39","modified_gmt":"2018-09-29T09:04:39","slug":"kro-avec-une-temperature-dautomne-enfin","status":"publish","type":"post","link":"http:\/\/blogs.bl0rg.net\/finis_africae\/2015\/09\/01\/kro-avec-une-temperature-dautomne-enfin\/","title":{"rendered":"Kro avec une temp\u00e9rature d&rsquo;automne, enfin"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2015\/09\/ACH003577070.1411530938.150x200-2015-08-5-22-09.jpg\" alt=\"ACH003577070.1411530938.150x200-2015-08-5-22-09.jpg\" width=\"124\" height=\"200\" \/><\/p>\n<p style=\"text-align: left;\">Enfin un peu de lecture.<\/p>\n<p style=\"text-align: left;\">Neal Stephenson : Les deux Mondes<\/p>\n<p style=\"text-align: left;\"><!--more--><\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\" alignright\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2015\/09\/DeuxMondes-1-Orange-2015-08-5-22-09.jpg\" alt=\"DeuxMondes-1-Orange-2015-08-5-22-09.jpg\" width=\"187\" height=\"293\" \/><strong>Neal Stephenson : Les deux Mondes (en anglais : Reamde)<\/strong><\/p>\n<p style=\"text-align: left;\">Richard Forthrast a fui l\u2019Iowa dans les ann\u00e9es 1970 pour \u00e9chapper \u00e0 la guerre du Vietnam.  <a href=\"https:\/\/www.nicn.fr\/\">Moncler doudounes femmes<\/a> R\u00e9fugi\u00e9 dans les Rocheuses canadiennes, il a fait fortune en important ill\u00e9galement de la marijuana sur le territoire am\u00e9ricain. Passionn\u00e9 de jeux vid\u00e9o, il y a ensuite investi une partie de son argent dans la soci\u00e9t\u00e9 Corporation 9592, qui exploite T\u2019Rain, un jeu en ligne de type World of warcraft, au succ\u00e8s international.  <a href=\"http:\/\/www.eglise-lavaur.fr\/\">Achat chaussure Puma<\/a> Voil\u00e0 qu\u2019un virus qui crypte des donn\u00e9es est utilis\u00e9 par un hacker chinois pour ran\u00e7onner les joueurs de T\u2019Rain.<\/p>\n<p style=\"text-align: left;\">L\u2019histoire va donc nous mener en Chine, l\u00e0 o\u00f9 des milliers de \u00ab gold farmers \u00bb jouent en permanence afin d\u2019acqu\u00e9rir des artefacts de T\u2019Rain, qu\u2019ils revendent ensuite aux joueurs occidentaux. L\u00e0 dessus, on va ajouter la mafia russe, d\u00e9pouill\u00e9e par hasard par le virus (Reamde), et un peu plus tard, nous ajouterons des Djihadistes.<\/p>\n<p style=\"text-align: left;\">D\u00e9crit comme \u00e7a, \u00e7a peut avoir l\u2019air fouille mais comme Stephenson est globalement un bon \u00e9crivain, \u00e7a ne l\u2019est pas et tout se tient sans confusion.<\/p>\n<p style=\"text-align: left;\">Stephenson est un excellent auteur de Cyberpunk ou de technothriller : l\u2019\u00e9norme avantage, quand on lit Stephenson, c\u2019est que ce qu\u2019il raconte est juste, informatiquement plausible.  <a href=\"https:\/\/www.manaespresso.fr\/\">ugg australia<\/a> Les hackers ne sont pas des super h\u00e9ros qui piratent les ordinateurs et vous espionnent \u00e0 travers la lumi\u00e8re verte du numlock.<\/p>\n<p style=\"text-align: left;\">Il est bien renseign\u00e9 : sur les jeux en ligne, les bitcoins et leur fonctionnement, le fonctionnement des virus, les arnaques informatiques. Et comme c\u2019est un gars s\u00e9rieux, je ne doute pas que ce qu\u2019il raconte sur les armes ou la navigation a\u00e9riennes est \u00e9galement juste.<\/p>\n<p style=\"text-align: left;\">Les critiques disent que ce livre va \u00e0 100 \u00e0 l\u2019heure&#8230;  <a href=\"http:\/\/www.bestofindia.fr\/soldes-puma-sneakers.html\">soldes puma sneakers<\/a> je ne suis pas tout \u00e0 fait d\u2019accord. Les longues sc\u00e8nes poursuites, traques, fuites, survie dans la nature m\u2019ont lass\u00e9e.  <a href=\"http:\/\/www.boulogne-vendee.fr\/\">chaussures puma<\/a> Bref, ce que j\u2019aime dans le technothriller, c\u2019est la techno, pas la fuite dans les bois.<\/p>\n<p style=\"text-align: left;\">Sinon, c\u2019est \u00e9crit avec l\u2019humour de Stephenson, avec son recul sur la technologie, sa vision plut\u00f4t juste des enjeux contemporains. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enfin un peu de lecture. Neal Stephenson : Les deux Mondes<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[53],"_links":{"self":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/6858"}],"collection":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/comments?post=6858"}],"version-history":[{"count":5,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/6858\/revisions"}],"predecessor-version":[{"id":8507,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/6858\/revisions\/8507"}],"wp:attachment":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/media?parent=6858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/categories?post=6858"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/tags?post=6858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}