{"id":7175,"date":"2016-09-04T22:37:27","date_gmt":"2016-09-04T20:37:27","guid":{"rendered":"http:\/\/blogs.bl0rg.net\/finis_africae\/?p=7175"},"modified":"2018-09-29T11:06:53","modified_gmt":"2018-09-29T09:06:53","slug":"salon-des-jeux-mathematiques","status":"publish","type":"post","link":"http:\/\/blogs.bl0rg.net\/finis_africae\/2016\/09\/04\/salon-des-jeux-mathematiques\/","title":{"rendered":"Salon des jeux math\u00e9matiques"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7176\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1717.jpg\" alt=\"IMG_1717\" width=\"320\" height=\"320\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1717.jpg 320w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1717-150x150.jpg 150w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1717-300x300.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/> Le salon des jeux math\u00e9matiques se tient \u00e0 Paris tous les ans depuis des ann\u00e9es (et je ne le savais m\u00eame pas). Le WE dernier, il \u00e9tait place St Sulpice. Il s&rsquo;est tenu au soleil vendredi et samedi, et sous l&rsquo;orage dimanche. Le salon est l&rsquo;occasion de rencontrer des math\u00e9maticiens barbu et chevelu qui viennent jouer avec les maths, des clones de Cedric Villani en redingote et lavalli\u00e8re  et des amateurs de jeux de plateau.  <a href=\"https:\/\/www.snuacte.fr\/moncler-pas-cher.html\">moncler pas cher<\/a> Villani a d&rsquo;ailleurs particip\u00e9 \u00e0 un d\u00e9bat vendredi soir, il y avait foule&#8230; du moins \u00e0 la hauteur d&rsquo;un salon de maths&#8230;  <a href=\"https:\/\/www.hotel-castel.fr\/ugg-soldes-2018.html\">ugg soldes 2018<\/a> ce qui \u00e0 un mois du foot, fait plaisir \u00e0 voir.  <a href=\"https:\/\/www.hotel-castel.fr\/\">bottes ugg<\/a> <!--more--> <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7179 aligncenter\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/kooba-300x253.png\" alt=\"kooba\" width=\"300\" height=\"253\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/kooba-300x253.png 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/kooba.png 619w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>J&rsquo;ai \u00e9t\u00e9 recrut\u00e9 pour jouer \u00e0 Kooba, un jeu mignon de bluff et d&rsquo;ench\u00e8res. <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-7186\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/ko-300x232.png\" alt=\"ko\" width=\"300\" height=\"232\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/ko-300x232.png 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/ko.png 483w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> Mais la majorit\u00e9 des jeux sont des jeux de logique, korridor, Awale, \u00e9chec, Quatro, et autre.  <a href=\"https:\/\/www.lutin-mickael.fr\/\">timberland pas cher<\/a> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-7181\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/mvt-300x186.png\" alt=\"mvt\" width=\"300\" height=\"186\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/mvt-300x186.png 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/mvt.png 530w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> On trouve toute sorte d&rsquo;associations sur le salon.  <a href=\"https:\/\/www.nicn.fr\/moncler-doudounes.html\">moncler Doudounes<\/a> Des associations qui font des maths ludiques avec les jeunes (comme Maths en jeans, mais plut\u00f4t des jeunes de terminal S), des soci\u00e9t\u00e9s savantes (Soci\u00e9t\u00e9 des math\u00e9maticiens de France, des maths appliqu\u00e9es, d&rsquo;informaticiens&#8230;) et des choses plus directement accessibles \u00e0 tous&#8230; Et d&rsquo;ailleurs, ce salon est rempli de filles et de gar\u00e7ons qui ont l&rsquo;air de bien s&rsquo;amuser. <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7182 aligncenter\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/pap-300x219.png\" alt=\"pap\" width=\"300\" height=\"219\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/pap-300x219.png 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/pap.png 631w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> On trouve \u00e9galement des maths artistiques mises en volume avec une imprimante 3D. <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7183 aligncenter\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1724-300x300.jpg\" alt=\"IMG_1724\" width=\"300\" height=\"300\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1724-300x300.jpg 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1724-150x150.jpg 150w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1724.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-7185\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/mand-276x300.png\" alt=\"mand\" width=\"276\" height=\"300\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/mand-276x300.png 276w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/mand.png 586w\" sizes=\"(max-width: 276px) 100vw, 276px\" \/> Depuis le temps que je connais les ensembles de Mandelbrot, je n\u2019en avais jamais vu en volume&#8230; Ces quelques images sont loin de repr\u00e9senter la diversit\u00e9 des stands. J&rsquo;ai m\u00eame crois\u00e9 le mathscope de l&rsquo;Universit\u00e9 de Gen\u00e8ve (une expo interactive pour inciter les lyc\u00e9ens \u00e0 s&rsquo;inscrire en fac de maths).  <a href=\"https:\/\/www.manaespresso.fr\/vente-privee-ugg.html\">vente privee ugg<\/a> Mon stand pr\u00e9f\u00e9r\u00e9, c&rsquo;\u00e9tait le stand de crypto : <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-7187\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1728-300x300.jpg\" alt=\"IMG_1728\" width=\"300\" height=\"300\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1728-300x300.jpg 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1728-150x150.jpg 150w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1728.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-7188\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1729-300x300.jpg\" alt=\"IMG_1729\" width=\"300\" height=\"300\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1729-300x300.jpg 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1729-150x150.jpg 150w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/IMG_1729.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> Avec de vraies machines de cryptographie de la 2e guerre mondiale qui fonctionne parfaitement avec une personne qui m&rsquo;a fait une d\u00e9mo rien que pour moi (parce qu&rsquo;il n&rsquo;y a pas tant de gens que \u00e7a que la crypto excite).  <a href=\"https:\/\/www.hotel-castel.fr\/sitemap.xml\">ugg sitemap<\/a> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-7190\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/liv-273x300.png\" alt=\"liv\" width=\"273\" height=\"300\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/liv-273x300.png 273w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/06\/liv.png 559w\" sizes=\"(max-width: 273px) 100vw, 273px\" \/>Bref, je me suis bien amus\u00e9e sur ce salon. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le salon des jeux math\u00e9matiques se tient \u00e0 Paris tous les ans depuis des ann\u00e9es (et je ne le savais m\u00eame pas). Le WE dernier, il \u00e9tait place St Sulpice. Il s&rsquo;est tenu au soleil vendredi et samedi, et sous &hellip; <a href=\"http:\/\/blogs.bl0rg.net\/finis_africae\/2016\/09\/04\/salon-des-jeux-mathematiques\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7175"}],"collection":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/comments?post=7175"}],"version-history":[{"count":4,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7175\/revisions"}],"predecessor-version":[{"id":8572,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7175\/revisions\/8572"}],"wp:attachment":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/media?parent=7175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/categories?post=7175"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/tags?post=7175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}