{"id":7288,"date":"2016-08-03T21:39:15","date_gmt":"2016-08-03T19:39:15","guid":{"rendered":"http:\/\/blogs.bl0rg.net\/finis_africae\/?p=7288"},"modified":"2016-08-03T21:39:15","modified_gmt":"2016-08-03T19:39:15","slug":"kro-vendee-t2-mode-keke-vs-hipster","status":"publish","type":"post","link":"http:\/\/blogs.bl0rg.net\/finis_africae\/2016\/08\/03\/kro-vendee-t2-mode-keke-vs-hipster\/","title":{"rendered":"Kro Vend\u00e9e, T2 : mode k\u00e9k\u00e9 vs hipster"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7291 size-full\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.45.17.png\" alt=\"Capture d\u2019\u00e9cran 2016-08-03 \u00e0 20.45.17\" width=\"780\" height=\"525\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.45.17.png 780w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.45.17-300x202.png 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.45.17-768x517.png 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/p>\n<p>La Vend\u00e9e, en ao\u00fbt, normalement, j&rsquo;y vais pas, y&rsquo;a trop de monde, m&rsquo;en fous, j&rsquo;y vais en janvier.<\/p>\n<p>N\u00e9anmoins, il faut reconna\u00eetre qu&rsquo;en janvier, m\u00eames circonstances exceptionnelles, les chances de bronzer sur la plage sont nulles. Alors, cette ann\u00e9e, j&rsquo;avais un cr\u00e9neau, tant pis je me suis lanc\u00e9e en ao\u00fbt, pr\u00eate \u00e0 affronter la foule, les bouchons et tourner 20 min pour me garer. Ci-dessus, la plage de St-Jean de Monts, \u00e0 14h. Certes, les gens vont arriver tout de m\u00eame un peu plus tard. Mais au mois d&rsquo;ao\u00fbt, c&rsquo;est \u00e9tonnant.<\/p>\n<p><!--more--><\/p>\n<p>Hier, il y a eu un peu de monde. Les touristes d&rsquo;ao\u00fbt sont un peu arriv\u00e9s. J&rsquo;ai m\u00eame renonc\u00e9 \u00e0 passer la Vie \u00e0 cause du bouchon allant du passage \u00e0 niveau jusqu&rsquo;au pont du man\u00e8ge. Mais c&rsquo;est la premi\u00e8re (et seule) fois. Alors qu&rsquo;il y a traditionnellement un bouchon end\u00e9mique quasiment \u00e0 toute heure que ce soit c\u00f4t\u00e9 port ou c\u00f4t\u00e9 marais.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-7292\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.51.00-210x300.png\" alt=\"Capture d\u2019\u00e9cran 2016-08-03 \u00e0 20.51.00\" width=\"210\" height=\"300\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.51.00-210x300.png 210w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.51.00.png 345w\" sizes=\"(max-width: 210px) 100vw, 210px\" \/>Est-ce les pok\u00e9mons aux abords des 5 pineaux qui leur ont fait peur ?<\/p>\n<p>Cette arriv\u00e9e de touriste m&rsquo;a permis d&rsquo;\u00e9tudier les conflits de style entre St Jean de Monts et Saint Gilles Croix de Vie.<\/p>\n<p>St Jean de Monts, c&rsquo;est populaire, c&rsquo;est m\u00eame volontiers la banlieue \u00e0 la plage. Leirnette\u00a0dirait : k\u00e9k\u00e9 land. Avec l&rsquo;arriv\u00e9e du tourisme, les k\u00e9k\u00e9 se sont un peu dilu\u00e9s au milieu des familles mais ils sont toujours l\u00e0. Dans la rue commer\u00e7ante, des\u00a0magasins leur sont plus particuli\u00e8rement adress\u00e9s, comme ce \u00ab\u00a0magasin de culotte\u00a0\u00bb et l\u00e0 encore, je cite Leirnette.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7293\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.55.46.png\" alt=\"Capture d\u2019\u00e9cran 2016-08-03 \u00e0 20.55.46\" width=\"565\" height=\"584\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.55.46.png 565w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-20.55.46-290x300.png 290w\" sizes=\"(max-width: 565px) 100vw, 565px\" \/><\/p>\n<p>Vous appr\u00e9cierez la subtilit\u00e9 des couleurs qui se confond avec la finesse des textes. J&rsquo;ai vu un oncle faire d\u00e9chiffrer \u00e0 sa ni\u00e8ce qui apprenait \u00e0 lire \u00ab\u00a0essai gratuit\u00a0\u00bb j&rsquo;ai failli appeler l&rsquo;aide \u00e0 l&rsquo;enfance.<\/p>\n<p>Le look k\u00e9k\u00e9, en gros c&rsquo;est le look sportif (plus c\u00f4t\u00e9 foot que c\u00f4t\u00e9 golf, hein), short en synth\u00e9tique \u00e0 3 bandes, grand T-shirt avec emmanchures super large, et surtout coupe de footballeur : ras\u00e9 en bas long en haut, maintenu par du gel \u00ab\u00a0effet mouill\u00e9\u00a0\u00bb. (J&rsquo;ai une th\u00e9orie au sujet de la coiffure des footballeurs. Je pense que les designers qui s&rsquo;occupaient des couvertures des livres de SF, ont d\u00e9cid\u00e9 de se reconvertir en cr\u00e9ateur de look de footballeurs, esp\u00e9rant d\u00e9goutter les gens du foot par attaque de ridicule. Malheureusement, c&rsquo;est un \u00e9chec : c&rsquo;est ridicule, mais de plus en plus pr\u00e9sent).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7295\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-21.22.05.png\" alt=\"Capture d\u2019\u00e9cran 2016-08-03 \u00e0 21.22.05\" width=\"698\" height=\"378\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-21.22.05.png 698w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-21.22.05-300x162.png 300w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>\n<p>Saint Gilles Croix de Vie, c&rsquo;est plus chic. Le look jeune dominant, c&rsquo;est hipster, reconnaissable par son allure vintage \u00e9tudi\u00e9e et sa barbe. Le probl\u00e8me avec moi, c&rsquo;est que je suis trop vieille pour appr\u00e9cier le hipster. Dans les ann\u00e9es 80, ce look ne ressemblait \u00e0 rien. D&rsquo;ailleurs, l&rsquo;informaticien brillant, mais socialement loser de \u00ab\u00a0Halt and catch fire\u00a0\u00bb a ce look (sans le bonnet mais avec la chemise \u00e0 carreaux). Et d\u00e8s qu&rsquo;il devient un homme d&rsquo;affaires, il comprend et\u00a0en\u00a0change pour avoir l&rsquo;air un peu s\u00e9rieux quand il passe \u00e0 la t\u00e9l\u00e9. Bref, voir r\u00e9apparaitre ce look aujourd&rsquo;hui me rappelle juste que je trouve qu&rsquo;il ressemble toujours \u00e0 rien.<\/p>\n<p>Ci-dessus : des versions possibles des sp\u00e9cimens. Sur la version hipster, le bonnet est facultatif en \u00e9t\u00e9 \u00e0 plage (mais tout \u00e0 fait possible \u00e0 l&rsquo;int\u00e9rieur d&rsquo;une l&rsquo;universit\u00e9, par exemple). Existe en version bicolore (cheveux blonds, barbe couleur d&rsquo;origine).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7297 alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-21.33.16-300x226.png\" alt=\"Capture d\u2019\u00e9cran 2016-08-03 \u00e0 21.33.16\" width=\"300\" height=\"226\" srcset=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-21.33.16-300x226.png 300w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-21.33.16-768x578.png 768w, http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/08\/Capture-d\u2019\u00e9cran-2016-08-03-\u00e0-21.33.16.png 795w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Pour finir : sans le moindre doute, Les Chouans reste une excellente cr\u00eaperie et\u00a0\u00e9tonnamment pas ch\u00e8re, vu sa notori\u00e9t\u00e9 et sa situation. C&rsquo;est le seule endroit o\u00f9 j&rsquo;ai vu faire la queue pour avoir une table \u00e0 20H.<\/p>\n<p>Ici, la c\u00e9l\u00e8bre galette ch\u00e8vre noix et pommes chaudes.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Vend\u00e9e, en ao\u00fbt, normalement, j&rsquo;y vais pas, y&rsquo;a trop de monde, m&rsquo;en fous, j&rsquo;y vais en janvier. N\u00e9anmoins, il faut reconna\u00eetre qu&rsquo;en janvier, m\u00eames circonstances exceptionnelles, les chances de bronzer sur la plage sont nulles. Alors, cette ann\u00e9e, j&rsquo;avais &hellip; <a href=\"http:\/\/blogs.bl0rg.net\/finis_africae\/2016\/08\/03\/kro-vendee-t2-mode-keke-vs-hipster\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[61],"_links":{"self":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7288"}],"collection":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/comments?post=7288"}],"version-history":[{"count":3,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7288\/revisions"}],"predecessor-version":[{"id":7298,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7288\/revisions\/7298"}],"wp:attachment":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/media?parent=7288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/categories?post=7288"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/tags?post=7288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}