{"id":7549,"date":"2016-10-30T18:48:10","date_gmt":"2016-10-30T16:48:10","guid":{"rendered":"http:\/\/blogs.bl0rg.net\/finis_africae\/?p=7549"},"modified":"2016-12-11T21:53:53","modified_gmt":"2016-12-11T19:53:53","slug":"kro-du-quebec-montreal-et-lile-bizard","status":"publish","type":"post","link":"http:\/\/blogs.bl0rg.net\/finis_africae\/2016\/10\/30\/kro-du-quebec-montreal-et-lile-bizard\/","title":{"rendered":"Kro du Qu\u00e9bec : Montr\u00e9al et l&rsquo;Ile Bizard"},"content":{"rendered":"<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/10\/biz-2016-10-30-17-48-1.png\" alt=\"biz-2016-10-30-17-48-1.png\" width=\"280\" height=\"179\" \/> J\u2019ai une amie qui habite sur l\u2019Ile Bizard, une petite \u00eele au nord de l\u2019Ile de Montr\u00e9al, dans le St Laurent. Elle porte ce nom parce qu\u2019elle appartenait \u00e0 Jacques Bizard, malgr\u00e9 tout,\u00a0le nom fait un peu r\u00eaver.<\/p>\n<p style=\"text-align: left;\">Au milieu de cette ile, un somptueux et prestigieux terrain de golf et un parc nature qui fait tout l\u2019int\u00e9r\u00eat de l\u2019ile.<\/p>\n<p style=\"text-align: left;\"><!--more--><\/p>\n<p style=\"text-align: left;\">On peut y voir des cerfs de Virginie, des ratons-laveurs, des renards. Malheureusement pour moi, les animaux n\u2019aiment pas tellement la pluie&#8230;<\/p>\n<p style=\"text-align: left;\">Je n\u2019ai gu\u00e8re vu que des \u00e9cureuils&#8230;<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/10\/ile-2016-10-30-17-48-1.png\" alt=\"ile-2016-10-30-17-48-1.png\" width=\"659\" height=\"479\" \/><\/p>\n<p style=\"text-align: left;\">Voici la plage de l\u2019Ile, il faut l\u2019imaginer l\u2019\u00e9t\u00e9, avec les gens qui nagent, les aires de pic-niques, les bateaux&#8230;<\/p>\n<p style=\"text-align: left;\">L\u2019ile est surtout r\u00e9sidentielle avec des propri\u00e9t\u00e9s somptueuses, qu\u2019on peine \u00e0 apercevoir au bout d\u2019un parc immense.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/10\/ile2-2016-10-30-17-48.png\" alt=\"ile2-2016-10-30-17-48.png\" width=\"514\" height=\"671\" \/><\/p>\n<p style=\"text-align: left;\">Mais il y a aussi une partie avec des gens qui habitent \u00e0 l&rsquo;ann\u00e9e et qui d\u00e9corent pour l\u2019Halloween&#8230; C\u2019est tout de m\u00eame \u00e0 1h30 de Montr\u00e9al en voiture, et pas tout \u00e0 fait \u00e0 port\u00e9e des transports montr\u00e9alais.<\/p>\n<p style=\"text-align: left;\">Je n\u2019ai pas fait de photos de Montr\u00e9al, parce que je n\u2019y \u00e9tais que le temps d\u2019un congr\u00e8s, mais je r\u00e9p\u00e8te, c\u2019est une ville formidable.<\/p>\n<p style=\"text-align: left;\">Ce qui m\u2019a frapp\u00e9e, en cette saison, c\u2019est le nombre de sans-abris, mendiants, travellers, et personnes paum\u00e9s manifestement cam\u00e9s aux alentours de l\u2019UQAM (l\u2019Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al). Tout d\u2019abord, je me suis demand\u00e9e si c\u2019\u00e9tait une cons\u00e9quence de la crise, mais je crois plut\u00f4t que c\u2019est une cons\u00e9quence m\u00e9t\u00e9o : en hiver, il vaut mieux \u00eatre en ville : l\u2019UQAM est ouverte tard le soir, c\u2019est un vaste lieu avec des tables et des bancs, et bien s\u00fbr, il y a l\u2019immense ville souterraine.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2016\/10\/tim-hortons-new-cafe-restaurant-2016-10-30-17-48.jpg\" alt=\"tim-hortons-new-cafe-restaurant-2016-10-30-17-48.jpg\" width=\"300\" height=\"194\" \/><\/p>\n<p style=\"text-align: left;\">N\u00e9anmoins, il y a aussi une banlieue tr\u00e8s populaire au nord de Montr\u00e9al. Vendredi soir, je suis all\u00e9e prendre un caf\u00e9 avec un ma copine dans un Tim Horton : une chaine de magasin o\u00f9 on boit du caf\u00e9 (mauvais) et o\u00f9 on peut acheter aussi des viennoiseries industrielles grasses et sucr\u00e9es. Il y en a absolument partout au Qu\u00e9bec. Je cherche un \u00e9quivalent fran\u00e7ais&#8230; c\u2019est en gros la restauration qu\u2019on trouve dans une banale station service d\u2019autoroute.<\/p>\n<p style=\"text-align: left;\">Le vendredi soir, il y a des familles populaires qui viennent au Tim Horton, comme on vient au restaurant, comme on sort pour boire un verre.<\/p>\n<p style=\"text-align: left;\">Elles viennent aussi jouer aux cartes, parents et enfants. Il faut dire qu\u2019il n\u2019y a pas beaucoup d\u2019endroits pour se retrouver dans cette banlieue un peu lointaine, \u00e0 part des Mc do et des restaurants probablement beaucoup trop chers. Il n\u2019y a pas de pub ou m\u00eame de bars. C\u2019est le Tim Horton, situ\u00e9 sur un parking de centre commercial qui fait l\u2019affaire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019ai une amie qui habite sur l\u2019Ile Bizard, une petite \u00eele au nord de l\u2019Ile de Montr\u00e9al, dans le St Laurent. Elle porte ce nom parce qu\u2019elle appartenait \u00e0 Jacques Bizard, malgr\u00e9 tout,\u00a0le nom fait un peu r\u00eaver. Au milieu &hellip; <a href=\"http:\/\/blogs.bl0rg.net\/finis_africae\/2016\/10\/30\/kro-du-quebec-montreal-et-lile-bizard\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7549"}],"collection":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/comments?post=7549"}],"version-history":[{"count":3,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7549\/revisions"}],"predecessor-version":[{"id":7552,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/7549\/revisions\/7552"}],"wp:attachment":[{"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/media?parent=7549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/categories?post=7549"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/tags?post=7549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}