{"id":4327,"date":"2011-06-21T22:29:14","date_gmt":"2011-06-21T20:29:14","guid":{"rendered":"http:\/\/blogs.bl0rg.net\/finis_africae\/2011\/06\/21\/kro-prodigieuse\/"},"modified":"2011-06-21T23:34:13","modified_gmt":"2011-06-21T21:34:13","slug":"kro-prodigieuse","status":"publish","type":"post","link":"https:\/\/blogs.bl0rg.net\/finis_africae\/2011\/06\/21\/kro-prodigieuse\/","title":{"rendered":"Kro prodigieuse"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/06\/19709041.jpg-r_160_214-b_1_CFD7E1-f_jpg-q_x-20110405_042611-2011-06-21-22-29.jpg\" alt=\"19709041.jpg-r_160_214-b_1_CFD7E1-f_jpg-q_x-20110405_042611-2011-06-21-22-29.jpg\" width=\"160\" height=\"213\" \/><br \/>\nFilm : The Prodigies par Antoine Charreyron<\/p>\n<p>Kung Fu Panda 2 par Jennifer Yu<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/06\/19452904-2011-06-21-22-29.jpg\" alt=\"19452904-2011-06-21-22-29.jpg\" width=\"251\" height=\"334\" \/><\/p>\n<p><strong>Film : The Prodigies par Antoine Charreyron<\/strong><br \/>\nJimbo Farrar est un enfant surdou\u00e9. Lors d\u2019une sc\u00e8ne terrible de violence familiale, ses parents meurent&#8230; suicide ou meurtre ? en tout cas, le jeune Jimbo s\u2019accuse de leur mort. Il est recueilli par un riche m\u00e9c\u00e8ne qui poss\u00e8de une fondation pour surdou\u00e9s. Bien des ann\u00e9es plus tard, Jimbo, qui travaille pour la fondation, localise 5 jeunes surdou\u00e9s un peu partout dans monde. Comme lui, ils semblent \u00eatre dou\u00e9s de pouvoirs mentaux. Seulement les jeunes sont violemment agress\u00e9s dans Central park et d\u00e9cident ensuite de se venger de tous.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/06\/19743426.jpg-r_760_x-f_jpg-q_x-20110519_064353-2011-06-21-22-29.jpg\" alt=\"19743426.jpg-r_760_x-f_jpg-q_x-20110519_064353-2011-06-21-22-29.jpg\" width=\"697\" height=\"376\" \/><\/p>\n<p>Attention, une adaptation p\u00e9rilleuse&#8230; La nuit des enfants-rois est un roman culte pour nerds des ann\u00e9es 1980. On y trouve tous les ingr\u00e9dients pour faire r\u00eaver les jeunes nerds : des enfants surdou\u00e9s incompris qui se retrouvent gr\u00e2ce \u00e0 l\u2019informatique, \u00ab\u00a0un agent conversationnel\u00a0\u00bb tellement interactif qu\u2019on se demande s\u2019il n\u2019est pas conscient et qui est le meilleur \u00ab\u00a0pote\u00a0\u00bb du h\u00e9ros, ou\u00e9, mec ! des surdou\u00e9s bless\u00e9s qui font trembler le monde, via les ordinateurs&#8230; bref, du fantasme en tube. Je ne jetterai s\u00fbrement pas la pierre, j\u2019ai beaucoup aim\u00e9 le livre quand Lotin me l\u2019a fait lire.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/06\/o-the-prodigies-teaser-trailer-2011-06-21-22-29.jpg\" alt=\"o-the-prodigies-teaser-trailer-2011-06-21-22-29.jpg\" width=\"550\" height=\"311\" \/><\/p>\n<p>Alors, aller voir une adaptation d\u2019un film culte, c\u2019est toujours inqui\u00e9tant. D\u2019autant plus que des adaptations ont \u00e9t\u00e9 faites pour \u00ab\u00a0coller\u00a0\u00bb aux ados d\u2019aujourd\u2019hui&#8230; La grande diff\u00e9rence, il y a que que les enfants-rois de Lenteric n\u2019avait pas de super pouvoirs, ils \u00e9taient juste surdou\u00e9s, et encore plus quand ils sont r\u00e9unis. Ceux de Charreyron sont pass\u00e9s par Marvel : ils ont des super pouvoirs. C\u2019\u00e9tait une mani\u00e8re de diminuer la violence du film, en basculant dans le fantastique plut\u00f4t que dans le r\u00e9el. C\u2019est un peu dommage&#8230; mais le film est quand m\u00eame interdit au moins de 12 ans.<br \/>\nAlors \u00e7a g\u00e9n\u00e8re quelques sc\u00e8nes un peu ridicules de distributions de baffes avec des corps anim\u00e9s. Mais \u00e0 c\u00f4t\u00e9, il y a de vrais r\u00e9ussites visuelles, en particulier, parce que la technique employ\u00e9e, le Motion Capture, c\u2019est beau.<\/p>\n<p>Alors, que dire finalement ?<br \/>\nIl y a c\u00f4t\u00e9 jouissif \u00e0 voir certaines sc\u00e8nes du livre s\u2019animer, car le film est r\u00e9alis\u00e9 pour des gens pour qui ce livre a compt\u00e9&#8230; En particulier quand Jimbo joue avec son train \u00e9lectrique en discutant avec son ordi.<br \/>\nD\u2019apr\u00e8s Lotin, il y a plus de bon que de mauvais dans ce film. Et en temps que pure fan, on peut lui faire confiance.<\/p>\n<p><strong><br \/>\n<\/strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/06\/19723216.jpg-r_160_214-b_1_CFD7E1-f_jpg-q_x-20110421_042305-2011-06-21-22-29.jpg\" alt=\"19723216.jpg-r_160_214-b_1_CFD7E1-f_jpg-q_x-20110421_042305-2011-06-21-22-29.jpg\" width=\"160\" height=\"213\" \/><\/p>\n<p><strong>Kung Fu Panda 2 par Jennifer Yu<\/strong><\/p>\n<p><strong> <\/strong>Po est devenu le Guerrier Dragon. Avec les Cinq cyclones, il fait r\u00e9gner la paix dans le village. Mais voil\u00e0 qu\u2019un \u00e9v\u00e9nement va le ramener au drame de sa naissance&#8230; Car Po est un enfant adopt\u00e9 : son p\u00e8re, l\u2019oie, n\u2019est pas vraiment son p\u00e8re&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/06\/19757625.jpg-r_760_x-f_jpg-q_x-20110609_024718-2011-06-21-22-29.jpg\" alt=\"19757625.jpg-r_760_x-f_jpg-q_x-20110609_024718-2011-06-21-22-29.jpg\" width=\"700\" height=\"298\" \/><\/p>\n<p>Kung Fu Panda 2 se rapproche davantage des films de Kung Fu : les gens volent, annoncent les coups avant de frapper&#8230; Ca reste dr\u00f4le, et le Panda est bien sympa, mais c\u2019est quand m\u00eame moins bien que le 1. Et \u00e7a a beau s\u2019annoncer en Real 3D&#8230; ben, bof, hein comme d\u2019habitude, hein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Film : The Prodigies par Antoine Charreyron Kung Fu Panda 2 par Jennifer Yu &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[31,29],"_links":{"self":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/4327"}],"collection":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/comments?post=4327"}],"version-history":[{"count":2,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/4327\/revisions"}],"predecessor-version":[{"id":4328,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/4327\/revisions\/4328"}],"wp:attachment":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/media?parent=4327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/categories?post=4327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/tags?post=4327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}