{"id":4482,"date":"2011-08-05T11:00:28","date_gmt":"2011-08-05T09:00:28","guid":{"rendered":"http:\/\/blogs.bl0rg.net\/finis_africae\/2011\/08\/05\/kro-de-chester\/"},"modified":"2011-08-05T19:29:01","modified_gmt":"2011-08-05T17:29:01","slug":"kro-de-chester","status":"publish","type":"post","link":"https:\/\/blogs.bl0rg.net\/finis_africae\/2011\/08\/05\/kro-de-chester\/","title":{"rendered":"Kro de Chester"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/08\/IMGP7747-2011-08-5-11-00.jpg\" alt=\"IMGP7747-2011-08-5-11-00.jpg\" width=\"220\" height=\"293\" \/><br \/>\nChester est une ville \u00e0 la fronti\u00e8re du Pays de Galles. Elle est c\u00e9l\u00e8bre pour sa cath\u00e9drale anglicane en brique rouge et ses maisons \u00e0 colombage. Elles sont suppos\u00e9es dater du Moyen-Age mais elles ont toutes \u00e9t\u00e9 raval\u00e9es voire reconstruite au XIXe. Peu importe, elles sont tr\u00e8s jolies.<br \/>\nUne grande rue commer\u00e7ante la traverse et m\u00e8ne jusqu\u2019\u00e0 la Dee, la rivi\u00e8re. (Photos : Lotin)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/08\/IMGP7749-2011-08-5-11-00.jpg\" alt=\"IMGP7749-2011-08-5-11-00.jpg\" width=\"480\" height=\"360\" \/><\/p>\n<p>La Cath\u00e9drale \u00e9tait payante, bien s\u00fbr. Alors, on n\u2019a pas visit\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/08\/IMGP7763-2011-08-5-11-00.jpg\" alt=\"IMGP7763-2011-08-5-11-00.jpg\" width=\"360\" height=\"480\" \/><\/p>\n<p>Dans la rue commer\u00e7ante&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/08\/IMGP7775-2011-08-5-11-00.jpg\" alt=\"IMGP7775-2011-08-5-11-00.jpg\" width=\"480\" height=\"413\" \/><\/p>\n<p>Le pont sur la Dee&#8230;<\/p>\n<p>A Chester, il y a un somptueux aquarium, kroniqu\u00e9 par Leirnette :<\/p>\n<p>Donc apr\u00e8s notre visite de Chester, nous sommes all\u00e9s visiter un aquarium non loin de l\u00e0.<br \/>\nSur la brochure prise au Bed &amp; Breakfast il d\u00e9j\u00e0 l&rsquo;air attrayant, mais l&rsquo;int\u00e9rieur \u00e9tait encore mieux que pr\u00e9vu &#8230; Par exemple, sur la brochure il n&rsquo;\u00e9tait pas fait mention d&rsquo;un tunnel transparent, o\u00f9 l&rsquo;on pouvait admirer les requins, raies, mur\u00e8nes, et autres d\u00e9cors sous-marin magnifiques ! Toute cette visite sous l&rsquo;oc\u00e9an se passait sur un tapis roulant qui nous amenait d&rsquo;un bout \u00e0 l&rsquo;autre du tunnel.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/08\/IMGP7820-2011-08-5-11-00.jpg\" alt=\"IMGP7820-2011-08-5-11-00.jpg\" width=\"360\" height=\"480\" \/><\/p>\n<p>Mis \u00e0 part ce moment paradisiaque, on change tout de suite d&rsquo;univers dans la partie vivarium du b\u00e2timent, o\u00f9 l&rsquo;on part \u00e0 la rencontre de la famille des arachnides. Mais malheureusement, la plupart de celles-ci \u00e9tant tout de m\u00eame petites, nous n&rsquo;avons pu voir qu&rsquo;une mygale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/08\/IMGP7796-2011-08-5-11-00.jpg\" alt=\"IMGP7796-2011-08-5-11-00.jpg\" width=\"480\" height=\"469\" \/><\/p>\n<p>Apr\u00e8s ce petit \u00e9pisode \u00ab\u00a0arachn\u00e9en\u00a0\u00bb nous avons pu admirer de petites mais tr\u00e8s mignonnes grenouilles venimeuses color\u00e9es de tr\u00e8s belles couleurs et rayures. Nous avons aussi fait la connaissance d&rsquo;un cam\u00e9l\u00e9on, dont Lotin a put tirer de belles photos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogs.bl0rg.net\/finis_africae\/wp-content\/uploads\/2011\/08\/IMGP7809-2011-08-5-11-00.jpg\" alt=\"IMGP7809-2011-08-5-11-00.jpg\" width=\"480\" height=\"360\" \/><\/p>\n<p>Cet aquarium remplis de surprises est tr\u00e8s beau \u00e0 voir, donc je le conseille \u00e0 quiconque pourrait s&rsquo;y rendre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chester est une ville \u00e0 la fronti\u00e8re du Pays de Galles. Elle est c\u00e9l\u00e8bre pour sa cath\u00e9drale anglicane en brique rouge et ses maisons \u00e0 colombage. Elles sont suppos\u00e9es dater du Moyen-Age mais elles ont toutes \u00e9t\u00e9 raval\u00e9es voire reconstruite &hellip; <a href=\"https:\/\/blogs.bl0rg.net\/finis_africae\/2011\/08\/05\/kro-de-chester\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,74,2],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/4482"}],"collection":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/comments?post=4482"}],"version-history":[{"count":3,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/4482\/revisions"}],"predecessor-version":[{"id":4486,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/posts\/4482\/revisions\/4486"}],"wp:attachment":[{"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/media?parent=4482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/categories?post=4482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/finis_africae\/wp-json\/wp\/v2\/tags?post=4482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}