{"id":24,"count":275,"description":"O\u00f9 le lecteur s'\u00e9merveille devant les subtilit\u00e9s du langage et la justesse de certains propos.","link":"https:\/\/blogs.bl0rg.net\/imaginos\/category\/parler\/","name":"Fa\u00e7on de parler","slug":"parler","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/categories\/24"}],"collection":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}