{"id":47758,"date":"2026-04-04T22:28:26","date_gmt":"2026-04-04T21:28:26","guid":{"rendered":"https:\/\/blogs.bl0rg.net\/imaginos\/?p=47758"},"modified":"2026-04-07T23:37:13","modified_gmt":"2026-04-07T22:37:13","slug":"folles-histoires-de-lespace","status":"publish","type":"post","link":"https:\/\/blogs.bl0rg.net\/imaginos\/2026\/04\/04\/folles-histoires-de-lespace\/","title":{"rendered":"Folles histoires de l&rsquo;espace"},"content":{"rendered":"\n<p class=\"justifier\">Depuis <a href=\"https:\/\/messagers-galactiques.tumblr.com\/telechargements\">cette page<\/a>, on peut t\u00e9l\u00e9charger diverses bricoles pour MEGA, dont le tout nouveau num\u00e9ro du bulletin galactique (le n\u00b0 9), qui fournit des \u00e9l\u00e9ments pour adapter divers films ou s\u00e9ries, dont Starcrash, San Ku Ka\u00ef et Barbarella.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis cette page, on peut t\u00e9l\u00e9charger diverses bricoles pour MEGA, dont le tout nouveau num\u00e9ro du bulletin galactique (le n\u00b0 9), qui fournit des \u00e9l\u00e9ments pour adapter divers films ou s\u00e9ries, dont Starcrash, San Ku Ka\u00ef et Barbarella.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1190,276,713],"_links":{"self":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/posts\/47758"}],"collection":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/comments?post=47758"}],"version-history":[{"count":2,"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/posts\/47758\/revisions"}],"predecessor-version":[{"id":47763,"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/posts\/47758\/revisions\/47763"}],"wp:attachment":[{"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/media?parent=47758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/categories?post=47758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bl0rg.net\/imaginos\/wp-json\/wp\/v2\/tags?post=47758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}